{"id":136,"count":7,"description":"","link":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/","name":"ink cartridge","slug":"ink-cartridge","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ink cartridge Archives - MapleJet India<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ink cartridge Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/\" \/>\n<meta property=\"og:site_name\" content=\"MapleJet India\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/tag\\\/ink-cartridge\\\/\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/tag\\\/ink-cartridge\\\/\",\"name\":\"ink cartridge Archives - MapleJet India\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/tag\\\/ink-cartridge\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/tag\\\/ink-cartridge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maplejet.com\\\/in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ink cartridge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#website\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/\",\"name\":\"MapleJet India\",\"description\":\"Industrial Inkjet Printer for coding and marking by\",\"publisher\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maplejet.com\\\/in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#organization\",\"name\":\"MapleJet India\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/12\\\/MapleJet-Logo-ArtWork-File-1.png\",\"contentUrl\":\"https:\\\/\\\/maplejet.com\\\/in\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/12\\\/MapleJet-Logo-ArtWork-File-1.png\",\"width\":806,\"height\":631,\"caption\":\"MapleJet India\"},\"image\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ink cartridge Archives - MapleJet India","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/","og_locale":"en_US","og_type":"article","og_title":"ink cartridge Archives","og_url":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/","og_site_name":"MapleJet India","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/","url":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/","name":"ink cartridge Archives - MapleJet India","isPartOf":{"@id":"https:\/\/maplejet.com\/in\/#website"},"breadcrumb":{"@id":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/maplejet.com\/in\/tag\/ink-cartridge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maplejet.com\/in\/"},{"@type":"ListItem","position":2,"name":"ink cartridge"}]},{"@type":"WebSite","@id":"https:\/\/maplejet.com\/in\/#website","url":"https:\/\/maplejet.com\/in\/","name":"MapleJet India","description":"Industrial Inkjet Printer for coding and marking by","publisher":{"@id":"https:\/\/maplejet.com\/in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maplejet.com\/in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maplejet.com\/in\/#organization","name":"MapleJet India","url":"https:\/\/maplejet.com\/in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maplejet.com\/in\/#\/schema\/logo\/image\/","url":"https:\/\/maplejet.com\/in\/wp-content\/uploads\/sites\/6\/2025\/12\/MapleJet-Logo-ArtWork-File-1.png","contentUrl":"https:\/\/maplejet.com\/in\/wp-content\/uploads\/sites\/6\/2025\/12\/MapleJet-Logo-ArtWork-File-1.png","width":806,"height":631,"caption":"MapleJet India"},"image":{"@id":"https:\/\/maplejet.com\/in\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/tags\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/posts?tags=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}