{"id":10633,"date":"2020-12-06T04:42:10","date_gmt":"2020-12-06T09:42:10","guid":{"rendered":"https:\/\/maplejet.com\/in\/?page_id=10633"},"modified":"2020-12-06T06:29:30","modified_gmt":"2020-12-06T11:29:30","slug":"login","status":"publish","type":"page","link":"https:\/\/maplejet.com\/in\/login\/","title":{"rendered":"Login"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f10636-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"10636\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/in\/wp-json\/wp\/v2\/pages\/10633#wpcf7-f10636-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"10636\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f10636-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<label> Email\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"your-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\n<label> Password\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-727\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"text-727\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-727\" \/><\/span>\n<\/label>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Login\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_raw_js]JTNDc2NyaXB0JTNFJTIwJTJGJTJGYWxlcnQlMjglMjAlMjJFbnRlciUyMHlvdXIlMjBqcyUyMGhlcmUlMjElMjIlMjAlMjklMEFkb2N1bWVudC5hZGRFdmVudExpc3RlbmVyJTI4JTIwJTI3d3BjZjdzdWJtaXQlMjclMkMlMjBmdW5jdGlvbiUyOCUyMGV2ZW50JTIwJTI5JTIwJTdCJTBBJTIwJTIwaWYlMjAlMjglMjAlMjcxMDYzNiUyNyUyMCUzRCUzRCUyMGV2ZW50LmRldGFpbC5jb250YWN0Rm9ybUlkJTIwJTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwJTJGJTJGYWxlcnQlMjglMjAlMjJUaGUlMjBjb250YWN0JTIwZm9ybSUyMElEJTIwaXMlMjAxMjMuJTIyJTIwJTI5JTNCJTBBJTIwJTIwJTIwJTIwJTJGJTJGJTIwZG8lMjBzb21ldGhpbmclMjBwcm9kdWN0aXZlJTBBJTIwJTIwJTdEJTBBdmFyJTIwaW5wdXRzJTIwJTNEJTIwZXZlbnQuZGV0YWlsLmlucHV0cyUzQiUwQSUyMCUwQSUyMCUyMGZvciUyMCUyOCUyMHZhciUyMGklMjAlM0QlMjAwJTNCJTIwaSUyMCUzQyUyMGlucHV0cy5sZW5ndGglM0IlMjBpJTJCJTJCJTIwJTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwaWYlMjAlMjglMjAlMjd0ZXh0LTcyNyUyNyUyMCUzRCUzRCUyMGlucHV0cyU1QmklNUQubmFtZSUyMCUyOSUyMCU3QiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyRiUyRmFsZXJ0JTI4JTIwaW5wdXRzJTVCaSU1RC52YWx1ZSUyMCUyOSUzQiUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMGFsZXJ0JTI4JTIyVXNlciUyMG5hbWUlMjBvciUyMHBhc3N3b3JkJTIweW91JTIwZW50ZXJlZCUyMGlzJTIwd3JvbmclMjIlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjBicmVhayUzQiUwQSUyMCUyMCUyMCUyMCU3RCUwQSUyMCUyMCU3RCUwQSUwQSUwQSU3RCUyQyUyMGZhbHNlJTIwJTI5JTNCJTBBJTBBJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10633","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Login - MapleJet India<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maplejet.com\/in\/login\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Login\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maplejet.com\/in\/login\/\" \/>\n<meta property=\"og:site_name\" content=\"MapleJet India\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-06T11:29:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maplejet.com\/in\/wp-content\/uploads\/sites\/6\/2020\/07\/mj-video-thumb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1091\" \/>\n\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/login\\\/\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/login\\\/\",\"name\":\"Login - MapleJet India\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#website\"},\"datePublished\":\"2020-12-06T09:42:10+00:00\",\"dateModified\":\"2020-12-06T11:29:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/login\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maplejet.com\\\/in\\\/login\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/login\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maplejet.com\\\/in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Login\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#website\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/\",\"name\":\"MapleJet India\",\"description\":\"Industrial Inkjet Printer for coding and marking by\",\"publisher\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maplejet.com\\\/in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#organization\",\"name\":\"MapleJet India\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maplejet.com\\\/in\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/12\\\/MapleJet-Logo-ArtWork-File-1.png\",\"contentUrl\":\"https:\\\/\\\/maplejet.com\\\/in\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/12\\\/MapleJet-Logo-ArtWork-File-1.png\",\"width\":806,\"height\":631,\"caption\":\"MapleJet India\"},\"image\":{\"@id\":\"https:\\\/\\\/maplejet.com\\\/in\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Login - MapleJet India","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maplejet.com\/in\/login\/","og_locale":"en_US","og_type":"article","og_title":"Login","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/maplejet.com\/in\/login\/","og_site_name":"MapleJet India","article_modified_time":"2020-12-06T11:29:30+00:00","og_image":[{"width":1091,"height":908,"url":"https:\/\/maplejet.com\/in\/wp-content\/uploads\/sites\/6\/2020\/07\/mj-video-thumb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maplejet.com\/in\/login\/","url":"https:\/\/maplejet.com\/in\/login\/","name":"Login - MapleJet India","isPartOf":{"@id":"https:\/\/maplejet.com\/in\/#website"},"datePublished":"2020-12-06T09:42:10+00:00","dateModified":"2020-12-06T11:29:30+00:00","breadcrumb":{"@id":"https:\/\/maplejet.com\/in\/login\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maplejet.com\/in\/login\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maplejet.com\/in\/login\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maplejet.com\/in\/"},{"@type":"ListItem","position":2,"name":"Login"}]},{"@type":"WebSite","@id":"https:\/\/maplejet.com\/in\/#website","url":"https:\/\/maplejet.com\/in\/","name":"MapleJet India","description":"Industrial Inkjet Printer for coding and marking by","publisher":{"@id":"https:\/\/maplejet.com\/in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maplejet.com\/in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maplejet.com\/in\/#organization","name":"MapleJet India","url":"https:\/\/maplejet.com\/in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maplejet.com\/in\/#\/schema\/logo\/image\/","url":"https:\/\/maplejet.com\/in\/wp-content\/uploads\/sites\/6\/2025\/12\/MapleJet-Logo-ArtWork-File-1.png","contentUrl":"https:\/\/maplejet.com\/in\/wp-content\/uploads\/sites\/6\/2025\/12\/MapleJet-Logo-ArtWork-File-1.png","width":806,"height":631,"caption":"MapleJet India"},"image":{"@id":"https:\/\/maplejet.com\/in\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/pages\/10633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/comments?post=10633"}],"version-history":[{"count":0,"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/pages\/10633\/revisions"}],"wp:attachment":[{"href":"https:\/\/maplejet.com\/in\/wp-json\/wp\/v2\/media?parent=10633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}